{"id":16799,"date":"2018-06-05T17:11:40","date_gmt":"2018-06-05T15:11:40","guid":{"rendered":"https:\/\/www.databack.fr\/senza-categoria\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/"},"modified":"2025-07-24T16:44:02","modified_gmt":"2025-07-24T14:44:02","slug":"come-puoi-ridurre-il-rischio-di-perdita-di-dati","status":"publish","type":"post","link":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/","title":{"rendered":"Come puoi ridurre il rischio di perdita di dati?"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-6033\" src=\"https:\/\/www.databack.fr\/wp-content\/uploads\/2018\/03\/1.4-perte-de-donnees.jpg.png\" alt=\"limite-rischio-perdita-dati\" width=\"600\" height=\"250\" srcset=\"https:\/\/www.databack.fr\/wp-content\/uploads\/2018\/03\/1.4-perte-de-donnees.jpg.png 600w, https:\/\/www.databack.fr\/wp-content\/uploads\/2018\/03\/1.4-perte-de-donnees.jpg-300x125.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><br \/><em>I rischi e i volumi di perdita dei dati possono essere notevolmente ridotti. Tuttavia, qualsiasi strategia di riduzione del rischio deve essere adattata alle dimensioni, alle esigenze e, soprattutto, alle risorse finanziarie dell&#8217;azienda. Dalle misure preventive a quelle curative, ecco le principali disposizioni applicabili a tutti i profili. <\/em><\/p>\n<h2>Sensibilizzazione: buone pratiche informatiche<\/h2>\n<p>Le cattive pratiche informatiche aumentano la vulnerabilit\u00e0 dei dati: la condivisione di file su piattaforme aperte, il backup di file professionali su computer personali, il salvataggio di identificativi per la connessione automatica e cos\u00ec via.<\/p>\n<p><strong>Documentare<\/strong> <strong>le procedure informatiche<\/strong> e definire una <strong>carta delle buone pratiche <\/strong>non \u00e8 quindi sufficiente. Iniziative <strong>di formazione<\/strong> e <strong>sensibilizzazione<\/strong> degli utenti contribuiranno a garantire il rispetto e la rigorosa applicazione delle procedure.<\/p>\n<h2>Prevenzione: back-up e sicurezza informatica<\/h2>\n<p>L&#8217;obiettivo delle misure <strong>preventive<\/strong> \u00e8 quello di ridurre il rischio di incidenti, perdite o indisponibilit\u00e0 dei dati.<\/p>\n<p>Gli strumenti e i protocolli<strong> di sicurezza informatica<\/strong> proteggono innanzitutto la rete e i computer dell&#8217;azienda da possibili attacchi esterni o interni:<\/p>\n<ul>\n<li><strong>Controllo dell&#8217;accesso degli utenti<\/strong>: restrizioni basate sui privilegi degli utenti, modifica delle password o recupero delle sessioni quando un dipendente lascia l&#8217;azienda, ecc.<\/li>\n<li><strong>Strumenti di rilevamento e sicurezza<\/strong>: firewall, software antivirus, software di controllo e monitoraggio dei server, software di rilevamento delle intrusioni (IDS), ecc.<\/li>\n<li><strong>Aggiornamenti<\/strong> regolari del software e degli strumenti di sicurezza informatica!<\/li>\n<\/ul>\n<p>Una politica di <strong>backup dei dati<\/strong> faciliter\u00e0 il ripristino in caso di disastro. Deve essere definita in base a diversi criteri:<\/p>\n<ul>\n<li><strong>Identificazione<\/strong> dei dati: volumi, dati importanti, ecc.<\/li>\n<li><strong>Supporti di archiviazione<\/strong>: dischi rigidi, server, backup online, ecc.<\/li>\n<li><strong>Metodo di backup<\/strong>: backup completo, incrementale o differenziale<\/li>\n<li><strong>Frequenza di backup<\/strong>: duplicazione in tempo reale o backup programmato&#8230;<\/li>\n<\/ul>\n<h2>Anticipazioni: BCP e DRP<\/h2>\n<p>Il<a href=\"https:\/\/www.databack.fr\/it\/blog\/recupero-dati-pca-pra\/\" target=\"_blank\" rel=\"noopener noreferrer\"> <strong>Piano di continuit\u00e0 aziendale (BCP)<\/strong> <\/a>e il <a href=\"https:\/\/www.databack.fr\/it\/blog\/recupero-dati-pca-pra\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Piano di Ripresa dell&#8217;Attivit\u00e0 (BRP)<\/strong><\/a> sono progettati per garantire che i processi aziendali e\/o informatici possano essere mantenuti, di solito in modalit\u00e0 degradata, e poi ripresi normalmente in caso di crisi o disastro. Sebbene le misure definite nella stesura di un BCP\/BRP dipendano dalle caratteristiche specifiche dell&#8217;azienda, si applicano sempre alcuni consigli:<\/p>\n<ul>\n<li><strong>Immaginare<\/strong> scenari di crisi e il loro impatto sull&#8217;azienda.<\/li>\n<li><strong>Identificare<\/strong> le risorse e i dati critici dell&#8217;azienda.<\/li>\n<li><strong>Definisci<\/strong> i ruoli del team responsabile dell&#8217;implementazione del BCP\/DRP.<\/li>\n<li><strong>Adottare<\/strong> e <strong>testare<\/strong> regolarmente il BCP\/PRA.<\/li>\n<li><strong>Aggiornare<\/strong> il BCP\/ERP in linea con le modifiche all&#8217;infrastruttura aziendale.<\/li>\n<\/ul>\n<h2>Curativo: recupero dati<\/h2>\n<p>I dati del computer sono molto persistenti. Anche se erroneamente considerati definitivamente distrutti o persi, possono essere recuperati nella maggior parte delle situazioni.<\/p>\n<p>Il <strong>recupero dei dati<\/strong> deve comunque essere affidato a un <a href=\"https:\/\/www.databack.fr\/it\/blog\/recupero-dati-unattivita-specializzata\/\" target=\"_blank\" rel=\"noopener noreferrer\">esperto qualificato<\/a> in grado di effettuare una diagnosi precisa e di mettere in atto le risorse adeguate. Il consiglio di un fornitore di servizi specializzato ha la precedenza su qualsiasi altro tentativo di recupero, poich\u00e9 un intervento incontrollato rischia di aggravare il danno e di ridurre il volume dei dati che possono essere recuperati in un secondo momento.<\/p>\n<p>In caso di perdita di dati, ecco alcune cose da fare:<\/p>\n<ul>\n<li><strong>Spegni il supporto di memorizzazione<\/strong> non appena sospetti un guasto (rumore insolito dall&#8217;hard disk, odore di bruciato, ecc.), un disastro o un grave errore di sistema.<\/li>\n<li><strong>Non eseguire operazioni software<\/strong> sul supporto di memorizzazione, come l&#8217;esecuzione di uno strumento di riparazione del sistema (CHKDSK), l&#8217;installazione di software, la reinstallazione o la formattazione del sistema, ecc.<\/li>\n<li><strong>Non utilizzare software di recupero dati<\/strong>, la maggior parte dei quali \u00e8 configurata per guasti specifici o per un errore di impostazione dei parametri che potrebbe peggiorare la situazione.<\/li>\n<li><strong>Non intervenire fisicamente<\/strong> sul supporto di memorizzazione, come ad esempio aprire un disco rigido, usare un asciugacapelli su un supporto di memorizzazione umido, ecc.<\/li>\n<li><strong>Ripristina i backup<\/strong> che hai su un supporto o un volume diverso.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-blanc-color has-orange-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.databack.fr\/it\/preventivo-gratuito\/\">Richiedi un preventivo gratuito<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>I rischi e i volumi di perdita dei dati possono essere notevolmente ridotti. Tuttavia, qualsiasi strategia di riduzione del rischio deve essere adattata alle dimensioni, alle esigenze e, soprattutto, alle risorse finanziarie dell&#8217;azienda. Dalle misure preventive a quelle curative, ecco le principali disposizioni applicabili a tutti i profili. Sensibilizzazione: buone pratiche informatiche Le cattive pratiche [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":17984,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131,76],"tags":[111],"ppma_author":[136,148],"class_list":["post-16799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-recupero-dati","tag-1-4-it","author-benoit-jaunet","author-benoit-jaunet-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come puoi ridurre il rischio di perdita di dati? - DATABACK<\/title>\n<meta name=\"description\" content=\"Ridurre i rischi di perdita dati \u00e8 possibile, ma ogni strategia deve tener conto delle dimensioni, delle esigenze e delle risorse economiche dell\u2019azienda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come puoi ridurre il rischio di perdita di dati? - DATABACK\" \/>\n<meta property=\"og:description\" content=\"Ridurre i rischi di perdita dati \u00e8 possibile, ma ogni strategia deve tener conto delle dimensioni, delle esigenze e delle risorse economiche dell\u2019azienda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/\" \/>\n<meta property=\"og:site_name\" content=\"Databack\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-05T15:11:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T14:44:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.databack.fr\/wp-content\/uploads\/2018\/06\/limiter-risques-perte-donnees.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Benoit Jaunet, Benoit Jaunet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Benoit Jaunet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come puoi ridurre il rischio di perdita di dati? - DATABACK","description":"Ridurre i rischi di perdita dati \u00e8 possibile, ma ogni strategia deve tener conto delle dimensioni, delle esigenze e delle risorse economiche dell\u2019azienda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/","og_locale":"it_IT","og_type":"article","og_title":"Come puoi ridurre il rischio di perdita di dati? - DATABACK","og_description":"Ridurre i rischi di perdita dati \u00e8 possibile, ma ogni strategia deve tener conto delle dimensioni, delle esigenze e delle risorse economiche dell\u2019azienda.","og_url":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/","og_site_name":"Databack","article_published_time":"2018-06-05T15:11:40+00:00","article_modified_time":"2025-07-24T14:44:02+00:00","og_image":[{"width":400,"height":267,"url":"https:\/\/www.databack.fr\/wp-content\/uploads\/2018\/06\/limiter-risques-perte-donnees.png","type":"image\/png"}],"author":"Benoit Jaunet, Benoit Jaunet","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Benoit Jaunet","Tempo di lettura stimato":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/#article","isPartOf":{"@id":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/"},"author":{"name":"Benoit Jaunet","@id":"https:\/\/www.databack.fr\/it\/#\/schema\/person\/160c17ae25712502025ccd4cbdd63b44"},"headline":"Come puoi ridurre il rischio di perdita di dati?","datePublished":"2018-06-05T15:11:40+00:00","dateModified":"2025-07-24T14:44:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/"},"wordCount":634,"publisher":{"@id":"https:\/\/www.databack.fr\/it\/#organization"},"image":{"@id":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.databack.fr\/wp-content\/uploads\/2018\/06\/limiter-risques-perte-donnees.png","keywords":["1.4"],"articleSection":["BLOG","Recupero dati"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/","url":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/","name":"Come puoi ridurre il rischio di perdita di dati? - DATABACK","isPartOf":{"@id":"https:\/\/www.databack.fr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/#primaryimage"},"image":{"@id":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.databack.fr\/wp-content\/uploads\/2018\/06\/limiter-risques-perte-donnees.png","datePublished":"2018-06-05T15:11:40+00:00","dateModified":"2025-07-24T14:44:02+00:00","description":"Ridurre i rischi di perdita dati \u00e8 possibile, ma ogni strategia deve tener conto delle dimensioni, delle esigenze e delle risorse economiche dell\u2019azienda.","breadcrumb":{"@id":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/#primaryimage","url":"https:\/\/www.databack.fr\/wp-content\/uploads\/2018\/06\/limiter-risques-perte-donnees.png","contentUrl":"https:\/\/www.databack.fr\/wp-content\/uploads\/2018\/06\/limiter-risques-perte-donnees.png","width":400,"height":267,"caption":"limiter la perte de donn\u00e9es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.databack.fr\/it\/blog\/come-puoi-ridurre-il-rischio-di-perdita-di-dati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"R\u00e9cup\u00e9ration de donn\u00e9es","item":"https:\/\/www.databack.fr\/it\/"},{"@type":"ListItem","position":2,"name":"Come puoi ridurre il rischio di perdita di dati?"}]},{"@type":"WebSite","@id":"https:\/\/www.databack.fr\/it\/#website","url":"https:\/\/www.databack.fr\/it\/","name":"Databack","description":"Laboratoire fran\u00e7ais de traitement de donn\u00e9es sensibles et volumineuses","publisher":{"@id":"https:\/\/www.databack.fr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.databack.fr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.databack.fr\/it\/#organization","name":"Databack","url":"https:\/\/www.databack.fr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.databack.fr\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.databack.fr\/wp-content\/uploads\/2025\/06\/favicon.png","contentUrl":"https:\/\/www.databack.fr\/wp-content\/uploads\/2025\/06\/favicon.png","width":512,"height":512,"caption":"Databack"},"image":{"@id":"https:\/\/www.databack.fr\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.databack.fr\/it\/#\/schema\/person\/160c17ae25712502025ccd4cbdd63b44","name":"Benoit Jaunet","description":"Beno\u00eet Jaunet rejoint DATABACK en 2010 en tant que charg\u00e9 d\u2019affaires. Interlocuteur privil\u00e9gi\u00e9 des clients particuliers comme professionnels, il joue un r\u00f4le central dans l\u2019\u00e9valuation des situations de perte de donn\u00e9es, l\u2019orientation des demandes vers les \u00e9quipes techniques et le suivi des projets de r\u00e9cup\u00e9ration. Gr\u00e2ce \u00e0 une connaissance fine des contraintes m\u00e9tiers et des contextes techniques vari\u00e9s, il contribue au quotidien \u00e0 \u00e9tablir une relation de confiance avec les clients et \u00e0 garantir un accompagnement clair, r\u00e9actif et transparent tout au long du processus.","sameAs":["https:\/\/www.linkedin.com\/in\/benoit-jaunet-1604847a\/"]}]}},"authors":[{"term_id":136,"user_id":12,"is_guest":0,"slug":"benoit-jaunet","display_name":"Benoit Jaunet","avatar_url":{"url":"https:\/\/www.databack.fr\/wp-content\/uploads\/2025\/06\/benoit-databack-scaled.jpg","url2x":"https:\/\/www.databack.fr\/wp-content\/uploads\/2025\/06\/benoit-databack-scaled.jpg"},"author_category":"1","first_name":"Benoit","last_name":"Jaunet","user_url":"https:\/\/www.linkedin.com\/in\/benoit-jaunet-1604847a\/","job_title":"CHARG\u00c9 D'AFFAIRES","description":"Beno\u00eet Jaunet rejoint <strong>DATABACK<\/strong> en 2010 en tant que charg\u00e9 d\u2019affaires. Interlocuteur privil\u00e9gi\u00e9 des clients particuliers comme professionnels, il joue un r\u00f4le central dans l\u2019\u00e9valuation des situations de perte de donn\u00e9es, l\u2019orientation des demandes vers les \u00e9quipes techniques et le suivi des projets de r\u00e9cup\u00e9ration.\r\n\r\nGr\u00e2ce \u00e0 une connaissance fine des contraintes m\u00e9tiers et des contextes techniques vari\u00e9s, il contribue au quotidien \u00e0 \u00e9tablir une relation de confiance avec les clients et \u00e0 garantir un accompagnement clair, r\u00e9actif et transparent tout au long du processus."},{"term_id":148,"user_id":0,"is_guest":1,"slug":"benoit-jaunet-it","display_name":"Benoit Jaunet","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","author_category":"","first_name":"","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/www.databack.fr\/it\/wp-json\/wp\/v2\/posts\/16799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.databack.fr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.databack.fr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.databack.fr\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.databack.fr\/it\/wp-json\/wp\/v2\/comments?post=16799"}],"version-history":[{"count":0,"href":"https:\/\/www.databack.fr\/it\/wp-json\/wp\/v2\/posts\/16799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.databack.fr\/it\/wp-json\/wp\/v2\/media\/17984"}],"wp:attachment":[{"href":"https:\/\/www.databack.fr\/it\/wp-json\/wp\/v2\/media?parent=16799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.databack.fr\/it\/wp-json\/wp\/v2\/categories?post=16799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.databack.fr\/it\/wp-json\/wp\/v2\/tags?post=16799"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.databack.fr\/it\/wp-json\/wp\/v2\/ppma_author?post=16799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}